{"id":2026,"date":"2014-12-10T10:40:14","date_gmt":"2014-12-10T10:40:14","guid":{"rendered":"http:\/\/elofhanssonfastigheter.dev2.mildmedia-dev.eu\/kunder\/?lang=en"},"modified":"2014-12-10T10:40:14","modified_gmt":"2014-12-10T10:40:14","slug":"kunder","status":"publish","type":"page","link":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/","title":{"rendered":"Kunder"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2026","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kunder - Elof Hansson<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kunder - Elof Hansson\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/\" \/>\n<meta property=\"og:site_name\" content=\"Elof Hansson\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/en\\\/kunder\\\/\",\"url\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/en\\\/kunder\\\/\",\"name\":\"Kunder - Elof Hansson\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/#website\"},\"datePublished\":\"2014-12-10T10:40:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/en\\\/kunder\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/en\\\/kunder\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/en\\\/kunder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kunder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/#website\",\"url\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/\",\"name\":\"Elof Hansson\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elofhanssonfastigheter.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kunder - Elof Hansson","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/","og_locale":"en_US","og_type":"article","og_title":"Kunder - Elof Hansson","og_url":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/","og_site_name":"Elof Hansson","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/","url":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/","name":"Kunder - Elof Hansson","isPartOf":{"@id":"https:\/\/www.elofhanssonfastigheter.com\/#website"},"datePublished":"2014-12-10T10:40:14+00:00","breadcrumb":{"@id":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elofhanssonfastigheter.com\/en\/kunder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elofhanssonfastigheter.com\/en\/"},{"@type":"ListItem","position":2,"name":"Kunder"}]},{"@type":"WebSite","@id":"https:\/\/www.elofhanssonfastigheter.com\/#website","url":"https:\/\/www.elofhanssonfastigheter.com\/","name":"Elof Hansson","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elofhanssonfastigheter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/pages\/2026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/comments?post=2026"}],"version-history":[{"count":0,"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/pages\/2026\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.elofhanssonfastigheter.com\/en\/wp-json\/wp\/v2\/media?parent=2026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}